{"id":2641,"date":"2016-12-03T20:50:29","date_gmt":"2016-12-03T19:50:29","guid":{"rendered":"http:\/\/psicopico.com\/?p=2641"},"modified":"2017-10-23T17:11:10","modified_gmt":"2017-10-23T16:11:10","slug":"analisis-puestos-trabajo","status":"publish","type":"post","link":"https:\/\/psicopico.com\/gl\/analisis-puestos-trabajo\/","title":{"rendered":"O an\u00e1lise do posto de traballo"},"content":{"rendered":"Os psic\u00f3logos te\u00f1en nos recursos humanos outra rama de especializaci\u00f3n cun amplo abanico de posibilidades, desde a selecci\u00f3n de persoal, o desenvolvemento de persoal, o coaching executivo ou a <a href=\"http:\/\/psicopico.com\/diferencias-orientacion-profesional-vocacional-laboral\/\"><strong>orientaci\u00f3n profesional<\/strong><\/a>, entre outras moitas funci\u00f3ns. Unha das funci\u00f3ns m\u00e1is importantes dos directores e xerentes de recursos humanos \u00e9 a an\u00e1lise de postos de traballo.<\/p>\n<h2>En que consiste a an\u00e1lise do posto de traballo?<\/h2>\n<p>A an\u00e1lise de postos de traballo \u00e9 aquel procedemento encargado de establecer as obrigaci\u00f3ns, competencias, habilidades e requisitos que require un determinado posto de traballo, as\u00ed como o tipo de persoas que se deben de contratar para ocupar o devandito posto.<\/p>\n<p>Con esta definici\u00f3n parece evidente que os co\u00f1ecementos sobre a conduta humana que achega a psicolox\u00eda son de suma importancia para interpretar que tipo de persoa e que caracter\u00edsticas ser\u00edan mellores para cubrir un posto espec\u00edfico. Por tanto, para poder acertar na selecci\u00f3n de persoal debemos co\u00f1ecer de forma exhaustiva que \u00e9 o que queremos contratar.<\/p>\n<blockquote><p>A an\u00e1lise de postos de traballo ten un car\u00e1cter preventivo na organizaci\u00f3n da empresa con m\u00faltiples beneficios derivados.<\/p><\/blockquote>\n<p>Moitas empresas non son conscientes do car\u00e1cter preventivo deste tipo de acci\u00f3ns para as s\u00faas econom\u00edas. Coa an\u00e1lise de postos e a correcta contrataci\u00f3n de persoal non s\u00f3 terminarase por aforrar en custo de contrataci\u00f3n (e despedimentos) sen\u00f3n que se mellora no desenvolvemento e planificaci\u00f3n da empresa. Confecci\u00f3nase unha correcta clasificaci\u00f3n dos postos de traballo e as s\u00faas tarefas. As\u00ed, cando unha persoa salga da t\u00faa empresa, saber\u00e1s de forma inmediata a que tipo de persoa necesitas contratar para cubrir a t\u00faa inminente necesidade, co que a contrataci\u00f3n ser\u00e1 m\u00e1is r\u00e1pida e eficiente.<\/p>\n<p>&gt;&gt; Artigo relacionado: <a href=\"http:\/\/psicopico.com\/la-entrevista-incidentes-criticos-i\/\">A entrevista de traballo de incidentes cr\u00edticos.<\/a><\/p>\n<p>\u00c9 dicir, mediante unha an\u00e1lise de postos de traballo cons\u00e9guese informaci\u00f3n relevante para elaborar a descrici\u00f3n do posto de traballo. Nesta descrici\u00f3n do posto sinal\u00e1sense as tarefas, obrigaci\u00f3ns, responsabilidades, condici\u00f3ns laborais, responsabilidades de supervisi\u00f3n, rep\u00f3rtelos e informes e as t\u00e9cnicas ou m\u00e1quinas usadas para cada caso.<\/p>\n<p>\u00c1 s\u00faa vez, da an\u00e1lise do posto re\u00fanese informaci\u00f3n sobre as especificaci\u00f3ns do posto, que son aqueles requisitos humanos necesarios para o posto: estudos, personalidade, habilidades sociais, certificaci\u00f3ns, habilidades t\u00e9cnicas, co\u00f1ecementos, etc.<\/p>\n<h3>Informaci\u00f3n que achega a an\u00e1lise de posto de traballo.<\/h3>\n<p>O especialista en recursos humanos reunir\u00e1 informaci\u00f3n referente aos seguintes puntos:<\/p>\n<ol>\n<li><strong>Actividades laborais<\/strong>. Tr\u00e1tase de contestar \u00e1s seguintes preguntas sobre a actividade que se realiza no posto: Que se fai? Como se fai? Por que se fai? Cando se fai? Como se fai? Non \u00e9 o mesmo vender reloxos que traballar nunha cadea de montaxe de coches.<\/li>\n<li><strong>Condutas humanas.<\/strong> Aqu\u00ed o que se busca \u00e9 reunir os datos sobre os comportamentos das persoas que realizan esa actividade. Ademais, d\u00e9bese de co\u00f1ecer o grao de esixencia do traballo (non \u00e9 o mesmo cargar sacos de cemento que traballar de teleoperador). Tratarase de co\u00f1ecer respostas \u00e1s capacidades de percibir, comunicar, redactar, decidir, cargar, etc.<\/li>\n<li><strong>Maquinaria, ferramentas, certificaci\u00f3ns<\/strong>. Neste aspecto re\u00fanese informaci\u00f3n sobre as necesidades m\u00e1is t\u00e9cnicas. Por exemplo, unha determinada m\u00e1quina ou utensilio e a s\u00faa capacidade para manexalo ou outro tipo de ferramentas m\u00e1is intangibles como \u00e9 o co\u00f1ecemento da persoa (econom\u00eda, dereito, psicolox\u00eda, deporte, inform\u00e1tica, etc.). Ademais, deberase co\u00f1ecer se o posto require de certas certificaci\u00f3ns espec\u00edficas (manipulador de alimentos, certificaci\u00f3n sanitaria, etc.).<\/li>\n<li><strong>Equipo e auxiliares de traballo.<\/strong> Moitos postos de traballo non se poden desempe\u00f1ar por si s\u00f3s e \u00e9 necesario saber as necesidades de auxiliares ou compa\u00f1eiros de traballo, operarios ao cargo ou superiores responsables.<\/li>\n<li><strong>Est\u00e1ndares de desempe\u00f1o<\/strong>. Para definir correctamente o posto \u00e9 necesario saber os est\u00e1ndares de desempe\u00f1o de cada tarefa. Por est\u00e1ndar de desempe\u00f1o ent\u00e9ndense, por exemplo, as caracter\u00edsticas ou niveis de calidade, cantidade, ou facturaci\u00f3n que esixe unha determinada tarefa. \u00c9 o que despois utilizar\u00e1n os directivos ou xerentes para poder avaliar o traballo realizado.<\/li>\n<li><strong>Contexto do posto.<\/strong> Aqu\u00ed tratarase de reunir a informaci\u00f3n referente ao ambiente e contexto social, organizacional, horarios de traballo ou condici\u00f3ns f\u00edsicas. Por exemplo, non \u00e9 o mesmo atender unha tenda de roupa cunha afluencia de p\u00fablico de 10 persoas ao d\u00eda que una na que entran 300.<\/li>\n<li><strong>Requisitos humanos.<\/strong> Neste apartado \u00e9 onde se recoller\u00e1 a informaci\u00f3n referente \u00e1s capacitaci\u00f3ns, estudos, experiencia laboral, competencias etc. Tam\u00e9n se sacar\u00e1 informaci\u00f3n sobre os atributos persoais para ese posto (caracter\u00edsticas f\u00edsicas, personalidade, intereses, aptitudes, idiomas, don de xentes, habilidades de negociaci\u00f3n, etc.)<\/li>\n<\/ol>\n<p>Toda esta informaci\u00f3n ser\u00e1 despois a que se utilizar\u00e1 no departamento de recursos humanos para o recrutamento e selecci\u00f3n de persoal, para as pol\u00edticas de remuneraci\u00f3ns e compensaci\u00f3ns por traballo realizado, programas de capacitaci\u00f3n e formaci\u00f3n interna, avaliaci\u00f3n do desempe\u00f1o, cumprir coa igualdade de oportunidades ou o que tam\u00e9n \u00e9 moi importante: descubrir tarefas ou obrigaci\u00f3ns que antes non estaban asignadas e que grazas a estas an\u00e1lises p\u00f3dense corrixir. Todo beneficios para a organizaci\u00f3n empresarial.<\/p>\n<p>&gt;&gt; Artigo relacionado:<a href=\"http:\/\/psicopico.com\/12-errores-del-entrevistador-la-seleccion-personal\/\"> Os 12 erros m\u00e1is frecuentes do entrevistador de persoal.<\/a><\/p>\n<p>_<\/p>\n<p><span style=\"font-size: 10pt;\">Referencias bibliogr\u00e1ficas:<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">Dessler G. (2009). <em>Administraci\u00f3n de Recursos Humanos.\u00a0<\/em>Pearson Educaci\u00f3n: M\u00e9xico.<\/span>","protected":false},"excerpt":{"rendered":"<p>Os psic\u00f3logos te\u00f1en nos recursos humanos outra rama de especializaci\u00f3n cun amplo abanico de posibilidades, desde a selecci\u00f3n de persoal, o desenvolvemento de persoal, o coaching executivo ou a orientaci\u00f3n profesional, entre outras moitas funci\u00f3ns. Unha das funci\u00f3ns m\u00e1is importantes dos directores e xerentes de recursos humanos \u00e9 a an\u00e1lise de postos de traballo. En [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2642,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[26],"tags":[362,71,11,361,178,346],"class_list":["post-2641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-organizaciones","tag-empresas","tag-organizaciones","tag-psicologia","tag-recursos-humanos","tag-seleccion-de-personal","tag-trabajo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O an\u00e1lise do posto de traballo - PsicoPico<\/title>\n<meta name=\"description\" content=\"El an\u00e1lisis de puestos de trabajo es una de las funciones m\u00e1s importantes de los departamentos de recursos humanos en la que los psic\u00f3logos tienen cabida.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/psicopico.com\/analisis-puestos-trabajo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O an\u00e1lise do posto de traballo - PsicoPico\" \/>\n<meta property=\"og:description\" content=\"El an\u00e1lisis de puestos de trabajo es una de las funciones m\u00e1s importantes de los departamentos de recursos humanos en la que los psic\u00f3logos tienen cabida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/psicopico.com\/analisis-puestos-trabajo\/\" \/>\n<meta property=\"og:site_name\" content=\"PsicoPico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/psicopicopsicologia\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/psicopicopsicologia\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-03T19:50:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-23T16:11:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/psicopico.com\/wp-content\/uploads\/2016\/12\/an\u00e1lisis-de-puestos-de-trabajo-work-analysis.jpg?fit=1280%2C853&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Iv\u00e1n Pico\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@psicopico\" \/>\n<meta name=\"twitter:site\" content=\"@psicopico\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Iv\u00e1n Pico\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/psicopico.com\\\/analisis-puestos-trabajo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/psicopico.com\\\/analisis-puestos-trabajo\\\/\"},\"author\":{\"name\":\"Iv\u00e1n Pico\",\"@id\":\"https:\\\/\\\/psicopico.com\\\/#\\\/schema\\\/person\\\/e90a6b8840bf0a67abfaa95093cbda44\"},\"headline\":\"O an\u00e1lise do posto de traballo\",\"datePublished\":\"2016-12-03T19:50:29+00:00\",\"dateModified\":\"2017-10-23T16:11:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/psicopico.com\\\/analisis-puestos-trabajo\\\/\"},\"wordCount\":2745,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/psicopico.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/psicopico.com\\\/analisis-puestos-trabajo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/psicopico.com\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/an%C3%A1lisis-de-puestos-de-trabajo-work-analysis.jpg?fit=1280%2C853&ssl=1\",\"keywords\":[\"empresas\",\"Organizaci\u00f3ns\",\"Psicolox\u00eda\",\"recursos humanos\",\"Selecci\u00f3n de Personal\",\"traballo\"],\"articleSection\":[\"Organizaci\u00f3ns\"],\"inLanguage\":\"gal-GAL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/psicopico.com\\\/analisis-puestos-trabajo\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/psicopico.com\\\/analisis-puestos-trabajo\\\/\",\"url\":\"https:\\\/\\\/psicopico.com\\\/analisis-puestos-trabajo\\\/\",\"name\":\"O an\u00e1lise do posto de traballo - PsicoPico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/psicopico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/psicopico.com\\\/analisis-puestos-trabajo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/psicopico.com\\\/analisis-puestos-trabajo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/psicopico.com\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/an%C3%A1lisis-de-puestos-de-trabajo-work-analysis.jpg?fit=1280%2C853&ssl=1\",\"datePublished\":\"2016-12-03T19:50:29+00:00\",\"dateModified\":\"2017-10-23T16:11:10+00:00\",\"description\":\"El an\u00e1lisis de puestos de trabajo es una de las funciones m\u00e1s importantes de los departamentos de recursos humanos en la que los psic\u00f3logos tienen cabida.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/psicopico.com\\\/analisis-puestos-trabajo\\\/#breadcrumb\"},\"inLanguage\":\"gal-GAL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/psicopico.com\\\/analisis-puestos-trabajo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gal-GAL\",\"@id\":\"https:\\\/\\\/psicopico.com\\\/analisis-puestos-trabajo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/psicopico.com\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/an%C3%A1lisis-de-puestos-de-trabajo-work-analysis.jpg?fit=1280%2C853&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/psicopico.com\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/an%C3%A1lisis-de-puestos-de-trabajo-work-analysis.jpg?fit=1280%2C853&ssl=1\",\"width\":\"1280\",\"height\":\"853\",\"caption\":\"an\u00e1lisis puestos de trabajo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/psicopico.com\\\/analisis-puestos-trabajo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/psicopico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El an\u00e1lisis de puestos de trabajo.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/psicopico.com\\\/#website\",\"url\":\"https:\\\/\\\/psicopico.com\\\/\",\"name\":\"PsicoPico\",\"description\":\"Psicopico - Psicolox\u00eda Online por Iv\u00e1n Pico\",\"publisher\":{\"@id\":\"https:\\\/\\\/psicopico.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/psicopico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gal-GAL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/psicopico.com\\\/#organization\",\"name\":\"Psicopico\",\"url\":\"https:\\\/\\\/psicopico.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gal-GAL\",\"@id\":\"https:\\\/\\\/psicopico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/psicopico.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/logowebpsicopico.png?fit=377%2C113&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/psicopico.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/logowebpsicopico.png?fit=377%2C113&ssl=1\",\"width\":\"377\",\"height\":\"113\",\"caption\":\"Psicopico\"},\"image\":{\"@id\":\"https:\\\/\\\/psicopico.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/psicopicopsicologia\\\/\",\"https:\\\/\\\/x.com\\\/psicopico\",\"https:\\\/\\\/instagram.com\\\/psicopico\",\"https:\\\/\\\/es.linkedin.com\\\/in\\\/iv\u00e1n-pico-mart\u00ednez-5bb46873\",\"https:\\\/\\\/www.pinterest.es\\\/psicopico\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwM4gAydCyOv_3sBkqVb74Q\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/psicopico.com\\\/#\\\/schema\\\/person\\\/e90a6b8840bf0a67abfaa95093cbda44\",\"name\":\"Iv\u00e1n Pico\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gal-GAL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db757e40cd044bc752196ef8f9c1ed3c3c79321f8c82624947f51448030b8af1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db757e40cd044bc752196ef8f9c1ed3c3c79321f8c82624947f51448030b8af1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db757e40cd044bc752196ef8f9c1ed3c3c79321f8c82624947f51448030b8af1?s=96&d=mm&r=g\",\"caption\":\"Iv\u00e1n Pico\"},\"description\":\"Director y creador de Psicopico.com. Psic\u00f3logo Colegiado G-5480. Graduado en Psicolog\u00eda. Diplomado en Ciencias Empresariales y M\u00e1ster en Orientaci\u00f3n Profesional. M\u00e1ster en Psicolog\u00eda del Trabajo y Organizaciones. Posgrado en Psicolog\u00eda del Deporte y Entrenador Profesional de Futsal Nivel 3. Visita la secci\u00f3n \\\"Sobre m\u00ed\\\"para saber m\u00e1s. \u00bfQuieres una consulta personalizada? \u00a1Contacta conmigo en https:\\\/\\\/ivanpico.es\\\/!\",\"sameAs\":[\"https:\\\/\\\/www.psicopico.com\",\"https:\\\/\\\/www.facebook.com\\\/psicopicopsicologia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/psicopico\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/ivan-pico-martinez\",\"https:\\\/\\\/x.com\\\/psicopico\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwM4gAydCyOv_3sBkqVb74Q\"],\"url\":\"https:\\\/\\\/psicopico.com\\\/gl\\\/author\\\/ivan-pico-psicologo-lugo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O an\u00e1lise do posto de traballo - PsicoPico","description":"El an\u00e1lisis de puestos de trabajo es una de las funciones m\u00e1s importantes de los departamentos de recursos humanos en la que los psic\u00f3logos tienen cabida.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/psicopico.com\/analisis-puestos-trabajo\/","og_locale":"en_US","og_type":"article","og_title":"O an\u00e1lise do posto de traballo - PsicoPico","og_description":"El an\u00e1lisis de puestos de trabajo es una de las funciones m\u00e1s importantes de los departamentos de recursos humanos en la que los psic\u00f3logos tienen cabida.","og_url":"https:\/\/psicopico.com\/analisis-puestos-trabajo\/","og_site_name":"PsicoPico","article_publisher":"https:\/\/es-la.facebook.com\/psicopicopsicologia\/","article_author":"https:\/\/www.facebook.com\/psicopicopsicologia\/","article_published_time":"2016-12-03T19:50:29+00:00","article_modified_time":"2017-10-23T16:11:10+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/i2.wp.com\/psicopico.com\/wp-content\/uploads\/2016\/12\/an\u00e1lisis-de-puestos-de-trabajo-work-analysis.jpg?fit=1280%2C853&ssl=1","type":"image\/jpeg"}],"author":"Iv\u00e1n Pico","twitter_card":"summary_large_image","twitter_creator":"@psicopico","twitter_site":"@psicopico","twitter_misc":{"Written by":"Iv\u00e1n Pico","Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/psicopico.com\/analisis-puestos-trabajo\/#article","isPartOf":{"@id":"https:\/\/psicopico.com\/analisis-puestos-trabajo\/"},"author":{"name":"Iv\u00e1n Pico","@id":"https:\/\/psicopico.com\/#\/schema\/person\/e90a6b8840bf0a67abfaa95093cbda44"},"headline":"O an\u00e1lise do posto de traballo","datePublished":"2016-12-03T19:50:29+00:00","dateModified":"2017-10-23T16:11:10+00:00","mainEntityOfPage":{"@id":"https:\/\/psicopico.com\/analisis-puestos-trabajo\/"},"wordCount":2745,"commentCount":0,"publisher":{"@id":"https:\/\/psicopico.com\/#organization"},"image":{"@id":"https:\/\/psicopico.com\/analisis-puestos-trabajo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/psicopico.com\/wp-content\/uploads\/2016\/12\/an%C3%A1lisis-de-puestos-de-trabajo-work-analysis.jpg?fit=1280%2C853&ssl=1","keywords":["empresas","Organizaci\u00f3ns","Psicolox\u00eda","recursos humanos","Selecci\u00f3n de Personal","traballo"],"articleSection":["Organizaci\u00f3ns"],"inLanguage":"gal-GAL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/psicopico.com\/analisis-puestos-trabajo\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/psicopico.com\/analisis-puestos-trabajo\/","url":"https:\/\/psicopico.com\/analisis-puestos-trabajo\/","name":"O an\u00e1lise do posto de traballo - PsicoPico","isPartOf":{"@id":"https:\/\/psicopico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/psicopico.com\/analisis-puestos-trabajo\/#primaryimage"},"image":{"@id":"https:\/\/psicopico.com\/analisis-puestos-trabajo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/psicopico.com\/wp-content\/uploads\/2016\/12\/an%C3%A1lisis-de-puestos-de-trabajo-work-analysis.jpg?fit=1280%2C853&ssl=1","datePublished":"2016-12-03T19:50:29+00:00","dateModified":"2017-10-23T16:11:10+00:00","description":"El an\u00e1lisis de puestos de trabajo es una de las funciones m\u00e1s importantes de los departamentos de recursos humanos en la que los psic\u00f3logos tienen cabida.","breadcrumb":{"@id":"https:\/\/psicopico.com\/analisis-puestos-trabajo\/#breadcrumb"},"inLanguage":"gal-GAL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/psicopico.com\/analisis-puestos-trabajo\/"]}]},{"@type":"ImageObject","inLanguage":"gal-GAL","@id":"https:\/\/psicopico.com\/analisis-puestos-trabajo\/#primaryimage","url":"https:\/\/i0.wp.com\/psicopico.com\/wp-content\/uploads\/2016\/12\/an%C3%A1lisis-de-puestos-de-trabajo-work-analysis.jpg?fit=1280%2C853&ssl=1","contentUrl":"https:\/\/i0.wp.com\/psicopico.com\/wp-content\/uploads\/2016\/12\/an%C3%A1lisis-de-puestos-de-trabajo-work-analysis.jpg?fit=1280%2C853&ssl=1","width":"1280","height":"853","caption":"an\u00e1lisis puestos de trabajo"},{"@type":"BreadcrumbList","@id":"https:\/\/psicopico.com\/analisis-puestos-trabajo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/psicopico.com\/"},{"@type":"ListItem","position":2,"name":"El an\u00e1lisis de puestos de trabajo."}]},{"@type":"WebSite","@id":"https:\/\/psicopico.com\/#website","url":"https:\/\/psicopico.com\/","name":"PsicoPico","description":"Psicopico - Psicolox\u00eda Online por Iv\u00e1n Pico","publisher":{"@id":"https:\/\/psicopico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/psicopico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gal-GAL"},{"@type":"Organization","@id":"https:\/\/psicopico.com\/#organization","name":"Psicopico","url":"https:\/\/psicopico.com\/","logo":{"@type":"ImageObject","inLanguage":"gal-GAL","@id":"https:\/\/psicopico.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/psicopico.com\/wp-content\/uploads\/2015\/12\/logowebpsicopico.png?fit=377%2C113&ssl=1","contentUrl":"https:\/\/i0.wp.com\/psicopico.com\/wp-content\/uploads\/2015\/12\/logowebpsicopico.png?fit=377%2C113&ssl=1","width":"377","height":"113","caption":"Psicopico"},"image":{"@id":"https:\/\/psicopico.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/psicopicopsicologia\/","https:\/\/x.com\/psicopico","https:\/\/instagram.com\/psicopico","https:\/\/es.linkedin.com\/in\/iv\u00e1n-pico-mart\u00ednez-5bb46873","https:\/\/www.pinterest.es\/psicopico\/","https:\/\/www.youtube.com\/channel\/UCwM4gAydCyOv_3sBkqVb74Q"]},{"@type":"Person","@id":"https:\/\/psicopico.com\/#\/schema\/person\/e90a6b8840bf0a67abfaa95093cbda44","name":"Iv\u00e1n Pico","image":{"@type":"ImageObject","inLanguage":"gal-GAL","@id":"https:\/\/secure.gravatar.com\/avatar\/db757e40cd044bc752196ef8f9c1ed3c3c79321f8c82624947f51448030b8af1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/db757e40cd044bc752196ef8f9c1ed3c3c79321f8c82624947f51448030b8af1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db757e40cd044bc752196ef8f9c1ed3c3c79321f8c82624947f51448030b8af1?s=96&d=mm&r=g","caption":"Iv\u00e1n Pico"},"description":"Director y creador de Psicopico.com. Psic\u00f3logo Colegiado G-5480. Graduado en Psicolog\u00eda. Diplomado en Ciencias Empresariales y M\u00e1ster en Orientaci\u00f3n Profesional. M\u00e1ster en Psicolog\u00eda del Trabajo y Organizaciones. Posgrado en Psicolog\u00eda del Deporte y Entrenador Profesional de Futsal Nivel 3. Visita la secci\u00f3n \"Sobre m\u00ed\"para saber m\u00e1s. \u00bfQuieres una consulta personalizada? \u00a1Contacta conmigo en https:\/\/ivanpico.es\/!","sameAs":["https:\/\/www.psicopico.com","https:\/\/www.facebook.com\/psicopicopsicologia\/","https:\/\/www.instagram.com\/psicopico\/","https:\/\/www.linkedin.com\/in\/ivan-pico-martinez","https:\/\/x.com\/psicopico","https:\/\/www.youtube.com\/channel\/UCwM4gAydCyOv_3sBkqVb74Q"],"url":"https:\/\/psicopico.com\/gl\/author\/ivan-pico-psicologo-lugo\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/psicopico.com\/wp-content\/uploads\/2016\/12\/an%C3%A1lisis-de-puestos-de-trabajo-work-analysis.jpg?fit=1280%2C853&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p6Zx58-GB","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/psicopico.com\/gl\/wp-json\/wp\/v2\/posts\/2641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/psicopico.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/psicopico.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/psicopico.com\/gl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/psicopico.com\/gl\/wp-json\/wp\/v2\/comments?post=2641"}],"version-history":[{"count":0,"href":"https:\/\/psicopico.com\/gl\/wp-json\/wp\/v2\/posts\/2641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/psicopico.com\/gl\/wp-json\/wp\/v2\/media\/2642"}],"wp:attachment":[{"href":"https:\/\/psicopico.com\/gl\/wp-json\/wp\/v2\/media?parent=2641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/psicopico.com\/gl\/wp-json\/wp\/v2\/categories?post=2641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/psicopico.com\/gl\/wp-json\/wp\/v2\/tags?post=2641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}